{"id":5305,"date":"2024-07-02T21:37:03","date_gmt":"2024-07-03T04:37:03","guid":{"rendered":"https:\/\/e-sais.com\/cajapopularrosario\/?page_id=1639"},"modified":"2025-11-25T17:59:47","modified_gmt":"2025-11-26T00:59:47","slug":"ahorro-garantia-liquida-2","status":"publish","type":"page","link":"https:\/\/e-sais.com\/cajapopularrosario\/ahorro-garantia-liquida-2\/","title":{"rendered":"Ahorro Garant\u00eda L\u00edquida"},"content":{"rendered":"\n  <div class=\"banner has-hover has-parallax\" id=\"banner-1262340135\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-5\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/e-sais.com\/cajapopularrosario\/wp-content\/uploads\/2025\/11\/ahorro-unisap.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\t<div class=\"img has-hover x50 md-x50 lg-x50 y20 md-y10 lg-y10\" id=\"image_1089643307\">\n\t\t\t\t\t\t<div data-animate=\"fadeInRight\">\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"422\" src=\"https:\/\/e-sais.com\/cajapopularrosario\/wp-content\/uploads\/2025\/11\/ahorro-garantia-liquida-logo-1024x424.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/e-sais.com\/cajapopularrosario\/wp-content\/uploads\/2025\/11\/ahorro-garantia-liquida-logo-1024x424.png 1024w, https:\/\/e-sais.com\/cajapopularrosario\/wp-content\/uploads\/2025\/11\/ahorro-garantia-liquida-logo-300x124.png 300w, https:\/\/e-sais.com\/cajapopularrosario\/wp-content\/uploads\/2025\/11\/ahorro-garantia-liquida-logo-768x318.png 768w, https:\/\/e-sais.com\/cajapopularrosario\/wp-content\/uploads\/2025\/11\/ahorro-garantia-liquida-logo.png 1220w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1089643307 {\n  width: 78%;\n}\n@media (min-width:550px) {\n  #image_1089643307 {\n    width: 44%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n   <div id=\"text-box-847168112\" class=\"text-box banner-layer x50 md-x50 lg-x50 y65 md-y70 lg-y70 res-text\">\n                     <div data-animate=\"fadeInUp\">           <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-center\">\n                  \n<div class=\"p-zgn4693 pagelayer-collapse pagelayer-animation-grow\">\n<div class=\"pagelayer-collapse-holder\" data-icon=\"fas fa-coins\" data-active_icon=\"fas fa-minus\">\n<div class=\"p-8hs7907 pagelayer-accordion_item active\">\n<div class=\"pagelayer-accordion-panel\">\n<div class=\"p-eyy379 pagelayer-inner_row pagelayer-row-stretch-auto pagelayer-height-default\">\n<div class=\"pagelayer-row-holder pagelayer-row pagelayer-auto pagelayer-width-auto\">\n<div class=\"p-gdk5348 pagelayer-col\">\n<div class=\"pagelayer-col-holder\">\n<div class=\"p-hn12471 pagelayer-list\">\n<div class=\"p-jpf8856 pagelayer-list_item\">\n<p><strong>Garant\u00eda financiera que respalda el cr\u00e9dito obtenido por un socio.\u00a0<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-847168112 .text-box-content {\n  background-color: rgba(255, 255, 255, 0.663);\n  font-size: 119%;\n}\n#text-box-847168112 .text-inner {\n  padding: 10px 10px 10px 10px;\n}\n#text-box-847168112 {\n  width: 62%;\n}\n@media (min-width:550px) {\n  #text-box-847168112 {\n    width: 34%;\n  }\n  #text-box-847168112 .text-box-content {\n    font-size: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1262340135 {\n  padding-top: 500px;\n}\n#banner-1262340135 .banner-bg img {\n  object-position: 0% 56%;\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_245575514\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1612126575\">\n\n\t<div id=\"col-247635724\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h1 style=\"text-align: left;\">RENDIMIENTOS<\/h1>\n<p style=\"text-align: left;\"><span style=\"font-size: 110%;\"><strong>-Tasa de inter\u00e9s anual fija 3.00%<\/strong><\/span>\u00a0\u00abAntes de Impuestos\u00bb.<br \/><strong>&#8211;\u00a0GAT<\/strong>\u00a0(Ganancia Anual Total).<br \/><strong>&#8211;\u00a0GAT nominal 3.04%<\/strong>\u00a0\u00abAntes de Impuestos\u00bb.<br \/><strong>&#8211; GAT real anual -0.80%<\/strong>\u00a0\u00abAntes de Impuestos\u00bb.<br \/>-Para fines informativos y de comparaci\u00f3n.\u00a0La\u00a0<strong>GAT\u00a0real<\/strong>\u00a0es el rendimiento que obtendr\u00eda despu\u00e9s de descontar la inflaci\u00f3n estimada.<br \/>&#8211; Fecha de c\u00e1lculo 11\/11\/2025.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1202367324\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h1 style=\"text-align: left;\">Caracter\u00edsticas<\/h1>\n<p style=\"text-align: left;\">Esta cuenta se apertura una vez que el socio adquiere un cr\u00e9dito con la cooperativa.<\/p>\n<p style=\"text-align: left;\">&#8211;\u00a0Saldo requerido de acuerdo a la reciprocidad del cr\u00e9dito.\u00a0<\/p>\n<p style=\"text-align: left;\">&#8211;\u00a0Sin cobro de comisiones.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_245575514 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 300px;\n  background-color: rgb(245, 245, 245);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section has-mask mask-arrow\" id=\"section_1050073176\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-2031293788\">\n\n\t<div id=\"col-1369931194\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"p-tzo1222 pagelayer-list\">\n<div class=\"p-bqm7342 pagelayer-list_item\">\n<h2 style=\"text-align: center;\">Generalidades<\/h2>\n<ul style=\"text-align: left;\">\n<li class=\"pagelayer-list-li\">\n<p>Para mayor informaci\u00f3n acuda con nuestros ejecutivos de servicios en cualquiera de las sucursales.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"p-ifl6145 pagelayer-list\" style=\"text-align: left;\">\n<div class=\"p-bwv9930 pagelayer-list_item\">\n<ul>\n<li class=\"pagelayer-list-li\">\n<p>Ahorro disponible en moneda nacional.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"p-c536675 pagelayer-list\" style=\"text-align: left;\">\n<div class=\"p-8qp2426 pagelayer-list_item\">\n<ul>\n<li class=\"pagelayer-list-li\">\n<p>Disponible en nuestras cuatro sucursales del Estado de Sinaloa, El Rosario, Escuinapa y Mazatl\u00e1n.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"p-yvm3049 pagelayer-list\">\n<div class=\"p-kb01597 pagelayer-list_item\">\n<ul>\n<li class=\"pagelayer-list-li\">\n<p style=\"text-align: left;\">Producto garantizado por el Fondo de Protecci\u00f3n a que se refiere el T\u00edtulo Cuarto de la Ley para Regular las Actividades de las Sociedades Cooperativas de Ahorro y Pr\u00e9stamo.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1050073176 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 300px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section has-mask mask-arrow\" id=\"section_775007503\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-357840972\">\n\n\t<div id=\"col-1016029960\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"p-tzo1222 pagelayer-list\">\n<div class=\"p-bqm7342 pagelayer-list_item\">\n<div class=\"p-bwc31 pagelayer-text fadeInRight pagelayer-wow\">\n<div class=\"pagelayer-text-holder\">\n<div class=\"p-bwc31 pagelayer-text fadeInRight pagelayer-wow\">\n<div class=\"pagelayer-text-holder\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 75%;\">\u201c\u00danicamente est\u00e1n garantizados por el Fondo de supervisi\u00f3n auxiliar de Sociedades Cooperativas de Ahorro y Pr\u00e9stamo y de protecci\u00f3n a sus ahorradores los dep\u00f3sitos de dinero: a la vista, de ahorro, a plazo fijo, retirables en d\u00edas preestablecidos o con previo aviso, hasta por el equivalente a 25 mil UDIS por persona f\u00edsica o moral, cualquiera que sea el n\u00famero y clase de operaciones a su favor y a cargo de una misma Instituci\u00f3n Financiera, en caso de que se declare su disoluci\u00f3n y liquidaci\u00f3n, o se declare su concurso mercantil.\u00a0Dicho fondo de protecci\u00f3n, cubrir\u00e1 el principal y accesorios de los dep\u00f3sitos de dinero referidos a la fecha en que se hubiere declarado la disoluci\u00f3n y liquidaci\u00f3n de la Sociedad Cooperativa de Ahorro y Pr\u00e9stamo o declarado su concurso mercantil, descontando el saldo insoluto de los pr\u00e9stamos o con respecto a los cuales sea deudor el Socio Ahorrador de que se trate, por lo que para estos efectos dichos pr\u00e9stamos o cr\u00e9ditos vencer\u00e1n de manera anticipada\u201d.\u00a0<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"p-onw141 pagelayer-text fadeInRight pagelayer-wow\">\n<div class=\"pagelayer-text-holder\">\n<section id=\"post-section\" class=\"post-section av-py-default blog-page\">\n<div class=\"av-container\">\n<div class=\"av-columns-area wow fadeInUp\">\n<div id=\"av-primary-content\" class=\"av-column-12 wow fadeInUp\">\n<div class=\"p-7mc660 pagelayer-row pagelayer-row-stretch-auto pagelayer-height-default\">\n<div class=\"pagelayer-row-holder pagelayer-row pagelayer-auto pagelayer-width-auto\">\n<div class=\"p-l6q9378 pagelayer-col\">\n<div class=\"pagelayer-col-holder\">\n<div class=\"p-onw141 pagelayer-text fadeInRight pagelayer-wow\">\n<div class=\"pagelayer-text-holder\">\n<p style=\"text-align: left;\"><span style=\"font-size: 80%;\"><strong>Equivalente del fondo de protecci\u00f3n a conversi\u00f3n en pesos moneda nacional\u00a0\u00a0$216,365.00 , calculado al 14 de Agosto del 2025.<\/strong><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_775007503 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 300px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-5305","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/pages\/5305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/comments?post=5305"}],"version-history":[{"count":34,"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/pages\/5305\/revisions"}],"predecessor-version":[{"id":9641,"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/pages\/5305\/revisions\/9641"}],"wp:attachment":[{"href":"https:\/\/e-sais.com\/cajapopularrosario\/wp-json\/wp\/v2\/media?parent=5305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}